{"id":23222,"date":"2017-12-12T18:32:47","date_gmt":"2017-12-12T17:32:47","guid":{"rendered":"http:\/\/www.garonehabitat.com\/?p=23222"},"modified":"2024-05-22T11:37:15","modified_gmt":"2024-05-22T09:37:15","slug":"infissi-antintrusione","status":"publish","type":"post","link":"https:\/\/garonehabitat.com\/en\/infissi-antintrusione\/","title":{"rendered":"INFISSI ANTINTRUSIONE RESISTENTI AI FURTI"},"content":{"rendered":"<p class=\"p1\"><span class=\"s1\"><img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-24550 alignright\" src=\"https:\/\/www.garonehabitat.com\/wp-content\/uploads\/2017\/12\/infissi-antintrusione-garone-habitat-300x169.jpg\" alt=\"\" width=\"300\" height=\"169\" srcset=\"https:\/\/garonehabitat.com\/wp-content\/uploads\/2017\/12\/infissi-antintrusione-garone-habitat-300x169.jpg 300w, https:\/\/garonehabitat.com\/wp-content\/uploads\/2017\/12\/infissi-antintrusione-garone-habitat-1030x580.jpg 1030w, https:\/\/garonehabitat.com\/wp-content\/uploads\/2017\/12\/infissi-antintrusione-garone-habitat-768x433.jpg 768w, https:\/\/garonehabitat.com\/wp-content\/uploads\/2017\/12\/infissi-antintrusione-garone-habitat-705x397.jpg 705w, https:\/\/garonehabitat.com\/wp-content\/uploads\/2017\/12\/infissi-antintrusione-garone-habitat.jpg 1200w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/>La presenza di un sistema di allarme non elimina del tutto il rischio di furti, mentre un sistema di chiusure di massima sicurezza protegge la casa dai malintenzionati.<\/span><\/p>\n<p class=\"p1\"><span class=\"s1\">Gli infissi antinstrusione dell\u2019azienda Garone Habitat, grazie alla ferramenta, ai vetri e alle opportune tecniche di posa in opera, sono in grado di opporre un\u2019efficace resistenza ai tentativi di scardinamento. <\/span><\/p>\n<p class=\"p1\"><span class=\"s1\">Garone Habitat offre infissi antintrusione, su richiesta dei clienti, con tre diversi livelli di sicurezza: un livello minimo, consigliato per le finestre di casa; un livello avanzato, adatto a contesti urbani e comunque non isolati; un livello massimo di sicurezza, indicato in contesti isolati.<\/span><\/p>\n<p class=\"p1\"><span class=\"s1\">Nel primo caso, grazie ai nottolini antistrappo in acciaio, capaci di sopportare spinte fino a 300 kg, i serramenti resistono alle tecniche di effrazione pi\u00f9 diffuse (sblocco delle maniglie e forzature delle finestre con calci, pugni o spallate).<\/span><\/p>\n<p class=\"p1\"><span class=\"s1\">Nel secondo caso, i serramenti sono in grado di resistere ai tentativi di forzatura con strumenti facili da reperire e da nascondere (cacciaviti, cunei, tenaglie e martelli). Gli infissi antitrusione superano le prove stabilite dalla normativa europea in Classe di Resistenza 2 (RC2). Il nottolino antistrappo chiude in speciali incontri in acciaio temprato e diventa un forte punto di chiusura che permette alla finestra di resistere a prove di scasso manuale, a spinte fino a 300 chilogrammi e a impatti dinamici con peso di 50 chilogrammi.<\/span><\/p>\n<p class=\"p1\"><span class=\"s1\">Nel terzo caso, i serramenti devono resistere allo scassinatore esperto ed attrezzato che tenta di entrare in casa, usando strumenti evoluti come: piede di porco, cacciavite, cunei, tenaglie e martelli. Gli infissi superano i test di scasso manuale, attacchi con piede di porco e spinte fino a 600 chilogrammi.<\/span><\/p>\n<p class=\"p1\"><span class=\"s1\">La chiusura di massima sicurezza, grazie al doppio granaio contrapposto in acciaio, impedisce al ladro di scardinare l\u2019anta sia per sollevamento che per strappo e resiste a prove di scasso, a spinte fino a 600 kg e a impatti dinamici con peso di 50 chilogrammi.\u00a0<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>La presenza di un sistema di allarme non elimina del tutto il rischio di furti, mentre un sistema di chiusure di massima sicurezza protegge la casa dai malintenzionati. Gli infissi antinstrusione dell\u2019azienda Garone Habitat, grazie alla ferramenta, ai vetri e alle opportune tecniche di posa in opera, sono in grado di opporre un\u2019efficace resistenza ai [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_joinchat":[],"footnotes":""},"categories":[2],"tags":[34,38,39,36],"class_list":["post-23222","post","type-post","status-publish","format-standard","hentry","category-news","tag-finestre","tag-porte","tag-portoni","tag-serramenti"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Infissi antintrusione - Garone-Habitat<\/title>\n<meta name=\"description\" content=\"Gli infissi antinstrusione, grazie alla ferramenta, ai vetri e alle tecniche di posa in opera, sono in grado di resistere ai tentativi di scardinamento.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/garonehabitat.com\/en\/infissi-antintrusione\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Infissi antintrusione - Garone-Habitat\" \/>\n<meta property=\"og:description\" content=\"Gli infissi antinstrusione, grazie alla ferramenta, ai vetri e alle tecniche di posa in opera, sono in grado di resistere ai tentativi di scardinamento.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/garonehabitat.com\/en\/infissi-antintrusione\/\" \/>\n<meta property=\"og:site_name\" content=\"Garone Habitat\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/GaroneHabitat\/\" \/>\n<meta property=\"article:published_time\" content=\"2017-12-12T17:32:47+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-05-22T09:37:15+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.garonehabitat.com\/wp-content\/uploads\/2017\/12\/infissi-antintrusione-garone-habitat-300x169.jpg\" \/>\n<meta name=\"author\" content=\"antoniosblendido\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"antoniosblendido\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/garonehabitat.com\\\/en\\\/infissi-antintrusione\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/garonehabitat.com\\\/en\\\/infissi-antintrusione\\\/\"},\"author\":{\"name\":\"antoniosblendido\",\"@id\":\"http:\\\/\\\/new.garonehabitat.com\\\/en\\\/#\\\/schema\\\/person\\\/caab3fc002c48efdd922e2b7bf350329\"},\"headline\":\"INFISSI ANTINTRUSIONE RESISTENTI AI FURTI\",\"datePublished\":\"2017-12-12T17:32:47+00:00\",\"dateModified\":\"2024-05-22T09:37:15+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/garonehabitat.com\\\/en\\\/infissi-antintrusione\\\/\"},\"wordCount\":321,\"commentCount\":0,\"publisher\":{\"@id\":\"http:\\\/\\\/new.garonehabitat.com\\\/en\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/garonehabitat.com\\\/en\\\/infissi-antintrusione\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.garonehabitat.com\\\/wp-content\\\/uploads\\\/2017\\\/12\\\/infissi-antintrusione-garone-habitat-300x169.jpg\",\"keywords\":[\"finestre\",\"porte\",\"portoni\",\"serramenti\"],\"articleSection\":[\"News\"],\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/garonehabitat.com\\\/en\\\/infissi-antintrusione\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/garonehabitat.com\\\/en\\\/infissi-antintrusione\\\/\",\"url\":\"https:\\\/\\\/garonehabitat.com\\\/en\\\/infissi-antintrusione\\\/\",\"name\":\"Infissi antintrusione - Garone-Habitat\",\"isPartOf\":{\"@id\":\"http:\\\/\\\/new.garonehabitat.com\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/garonehabitat.com\\\/en\\\/infissi-antintrusione\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/garonehabitat.com\\\/en\\\/infissi-antintrusione\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.garonehabitat.com\\\/wp-content\\\/uploads\\\/2017\\\/12\\\/infissi-antintrusione-garone-habitat-300x169.jpg\",\"datePublished\":\"2017-12-12T17:32:47+00:00\",\"dateModified\":\"2024-05-22T09:37:15+00:00\",\"description\":\"Gli infissi antinstrusione, grazie alla ferramenta, ai vetri e alle tecniche di posa in opera, sono in grado di resistere ai tentativi di scardinamento.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/garonehabitat.com\\\/en\\\/infissi-antintrusione\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/garonehabitat.com\\\/en\\\/infissi-antintrusione\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/garonehabitat.com\\\/en\\\/infissi-antintrusione\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.garonehabitat.com\\\/wp-content\\\/uploads\\\/2017\\\/12\\\/infissi-antintrusione-garone-habitat-300x169.jpg\",\"contentUrl\":\"https:\\\/\\\/www.garonehabitat.com\\\/wp-content\\\/uploads\\\/2017\\\/12\\\/infissi-antintrusione-garone-habitat-300x169.jpg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/garonehabitat.com\\\/en\\\/infissi-antintrusione\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/garonehabitat.com\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"INFISSI ANTINTRUSIONE RESISTENTI AI FURTI\"}]},{\"@type\":\"WebSite\",\"@id\":\"http:\\\/\\\/new.garonehabitat.com\\\/en\\\/#website\",\"url\":\"http:\\\/\\\/new.garonehabitat.com\\\/en\\\/\",\"name\":\"Garone Habitat\",\"description\":\"\",\"publisher\":{\"@id\":\"http:\\\/\\\/new.garonehabitat.com\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"http:\\\/\\\/new.garonehabitat.com\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"http:\\\/\\\/new.garonehabitat.com\\\/en\\\/#organization\",\"name\":\"Garone Habitat\",\"url\":\"http:\\\/\\\/new.garonehabitat.com\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"http:\\\/\\\/new.garonehabitat.com\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.garonehabitat.com\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/logo-white_garone-1.png\",\"contentUrl\":\"https:\\\/\\\/www.garonehabitat.com\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/logo-white_garone-1.png\",\"width\":149,\"height\":81,\"caption\":\"Garone Habitat\"},\"image\":{\"@id\":\"http:\\\/\\\/new.garonehabitat.com\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/GaroneHabitat\\\/\"]},{\"@type\":\"Person\",\"@id\":\"http:\\\/\\\/new.garonehabitat.com\\\/en\\\/#\\\/schema\\\/person\\\/caab3fc002c48efdd922e2b7bf350329\",\"name\":\"antoniosblendido\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/?s=96&d=mm&r=g\",\"caption\":\"antoniosblendido\"},\"url\":\"https:\\\/\\\/garonehabitat.com\\\/en\\\/author\\\/antoniosblendido\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Infissi antintrusione - Garone-Habitat","description":"Gli infissi antinstrusione, grazie alla ferramenta, ai vetri e alle tecniche di posa in opera, sono in grado di resistere ai tentativi di scardinamento.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/garonehabitat.com\/en\/infissi-antintrusione\/","og_locale":"en_US","og_type":"article","og_title":"Infissi antintrusione - Garone-Habitat","og_description":"Gli infissi antinstrusione, grazie alla ferramenta, ai vetri e alle tecniche di posa in opera, sono in grado di resistere ai tentativi di scardinamento.","og_url":"https:\/\/garonehabitat.com\/en\/infissi-antintrusione\/","og_site_name":"Garone Habitat","article_publisher":"https:\/\/www.facebook.com\/GaroneHabitat\/","article_published_time":"2017-12-12T17:32:47+00:00","article_modified_time":"2024-05-22T09:37:15+00:00","og_image":[{"url":"https:\/\/www.garonehabitat.com\/wp-content\/uploads\/2017\/12\/infissi-antintrusione-garone-habitat-300x169.jpg","type":"","width":"","height":""}],"author":"antoniosblendido","twitter_card":"summary_large_image","twitter_misc":{"Written by":"antoniosblendido","Est. reading time":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/garonehabitat.com\/en\/infissi-antintrusione\/#article","isPartOf":{"@id":"https:\/\/garonehabitat.com\/en\/infissi-antintrusione\/"},"author":{"name":"antoniosblendido","@id":"http:\/\/new.garonehabitat.com\/en\/#\/schema\/person\/caab3fc002c48efdd922e2b7bf350329"},"headline":"INFISSI ANTINTRUSIONE RESISTENTI AI FURTI","datePublished":"2017-12-12T17:32:47+00:00","dateModified":"2024-05-22T09:37:15+00:00","mainEntityOfPage":{"@id":"https:\/\/garonehabitat.com\/en\/infissi-antintrusione\/"},"wordCount":321,"commentCount":0,"publisher":{"@id":"http:\/\/new.garonehabitat.com\/en\/#organization"},"image":{"@id":"https:\/\/garonehabitat.com\/en\/infissi-antintrusione\/#primaryimage"},"thumbnailUrl":"https:\/\/www.garonehabitat.com\/wp-content\/uploads\/2017\/12\/infissi-antintrusione-garone-habitat-300x169.jpg","keywords":["finestre","porte","portoni","serramenti"],"articleSection":["News"],"inLanguage":"en-US","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/garonehabitat.com\/en\/infissi-antintrusione\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/garonehabitat.com\/en\/infissi-antintrusione\/","url":"https:\/\/garonehabitat.com\/en\/infissi-antintrusione\/","name":"Infissi antintrusione - Garone-Habitat","isPartOf":{"@id":"http:\/\/new.garonehabitat.com\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/garonehabitat.com\/en\/infissi-antintrusione\/#primaryimage"},"image":{"@id":"https:\/\/garonehabitat.com\/en\/infissi-antintrusione\/#primaryimage"},"thumbnailUrl":"https:\/\/www.garonehabitat.com\/wp-content\/uploads\/2017\/12\/infissi-antintrusione-garone-habitat-300x169.jpg","datePublished":"2017-12-12T17:32:47+00:00","dateModified":"2024-05-22T09:37:15+00:00","description":"Gli infissi antinstrusione, grazie alla ferramenta, ai vetri e alle tecniche di posa in opera, sono in grado di resistere ai tentativi di scardinamento.","breadcrumb":{"@id":"https:\/\/garonehabitat.com\/en\/infissi-antintrusione\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/garonehabitat.com\/en\/infissi-antintrusione\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/garonehabitat.com\/en\/infissi-antintrusione\/#primaryimage","url":"https:\/\/www.garonehabitat.com\/wp-content\/uploads\/2017\/12\/infissi-antintrusione-garone-habitat-300x169.jpg","contentUrl":"https:\/\/www.garonehabitat.com\/wp-content\/uploads\/2017\/12\/infissi-antintrusione-garone-habitat-300x169.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/garonehabitat.com\/en\/infissi-antintrusione\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/garonehabitat.com\/en\/"},{"@type":"ListItem","position":2,"name":"INFISSI ANTINTRUSIONE RESISTENTI AI FURTI"}]},{"@type":"WebSite","@id":"http:\/\/new.garonehabitat.com\/en\/#website","url":"http:\/\/new.garonehabitat.com\/en\/","name":"Garone Habitat","description":"","publisher":{"@id":"http:\/\/new.garonehabitat.com\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"http:\/\/new.garonehabitat.com\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"http:\/\/new.garonehabitat.com\/en\/#organization","name":"Garone Habitat","url":"http:\/\/new.garonehabitat.com\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"http:\/\/new.garonehabitat.com\/en\/#\/schema\/logo\/image\/","url":"https:\/\/www.garonehabitat.com\/wp-content\/uploads\/2024\/05\/logo-white_garone-1.png","contentUrl":"https:\/\/www.garonehabitat.com\/wp-content\/uploads\/2024\/05\/logo-white_garone-1.png","width":149,"height":81,"caption":"Garone Habitat"},"image":{"@id":"http:\/\/new.garonehabitat.com\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/GaroneHabitat\/"]},{"@type":"Person","@id":"http:\/\/new.garonehabitat.com\/en\/#\/schema\/person\/caab3fc002c48efdd922e2b7bf350329","name":"antoniosblendido","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/secure.gravatar.com\/avatar\/?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/?s=96&d=mm&r=g","caption":"antoniosblendido"},"url":"https:\/\/garonehabitat.com\/en\/author\/antoniosblendido\/"}]}},"_links":{"self":[{"href":"https:\/\/garonehabitat.com\/en\/wp-json\/wp\/v2\/posts\/23222","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/garonehabitat.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/garonehabitat.com\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/garonehabitat.com\/en\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/garonehabitat.com\/en\/wp-json\/wp\/v2\/comments?post=23222"}],"version-history":[{"count":3,"href":"https:\/\/garonehabitat.com\/en\/wp-json\/wp\/v2\/posts\/23222\/revisions"}],"predecessor-version":[{"id":24549,"href":"https:\/\/garonehabitat.com\/en\/wp-json\/wp\/v2\/posts\/23222\/revisions\/24549"}],"wp:attachment":[{"href":"https:\/\/garonehabitat.com\/en\/wp-json\/wp\/v2\/media?parent=23222"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/garonehabitat.com\/en\/wp-json\/wp\/v2\/categories?post=23222"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/garonehabitat.com\/en\/wp-json\/wp\/v2\/tags?post=23222"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}