{"id":27252,"date":"2024-05-17T14:11:50","date_gmt":"2024-05-17T12:11:50","guid":{"rendered":"http:\/\/garonehabitat.wp3.mtncompany.cloud\/?page_id=27252"},"modified":"2024-06-11T11:33:55","modified_gmt":"2024-06-11T09:33:55","slug":"cookie-privacy","status":"publish","type":"page","link":"https:\/\/garonehabitat.com\/es\/cookie-privacy\/","title":{"rendered":"Cookie &#038; Privacy"},"content":{"rendered":"<section  class='av_textblock_section av-lx35ikau-9e418e7df5e7cb0a5f755d176ba19de7 '   itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/CreativeWork\" ><div class='avia_textblock'  itemprop=\"text\" ><h1>Privacy Policy<\/h1>\n<p>Privacy Policy di www.garonehabitat.com<br \/>\nQuesta Applicazione raccoglie alcuni Dati Personali dei propri Utenti.<\/p>\n<p>Titolare del Trattamento dei Dati<br \/>\nGarone Habitat<br \/>\ninfo@garonehabitat.com<\/p>\n<p>Tipologie di Dati raccolti<br \/>\nFra i Dati Personali raccolti da questa Applicazione, in modo autonomo o tramite terze parti, ci sono: Email, Nome e Cognome.<br \/>\nAltri Dati Personali raccolti potrebbero essere indicati in altre sezioni di questa privacy policy o mediante testi informativi visualizzati contestualmente alla raccolta dei Dati stessi.<br \/>\nI Dati Personali possono essere inseriti volontariamente dall&#8217;Utente, oppure raccolti in modo automatico durante l&#8217;uso di questa Applicazione.<br \/>\nL\u2019eventuale utilizzo di Cookie &#8211; o di altri strumenti di tracciamento &#8211; da parte di questa Applicazione o dei titolari dei servizi terzi utilizzati da questa Applicazione, ove non diversamente precisato, ha la finalit\u00e0\u00a0 di identificare l&#8217;Utente e registrare le relative preferenze per finalit\u00e0\u00a0 strettamente legate all&#8217;erogazione del servizio richiesto dall&#8217;Utente.<br \/>\nIl mancato conferimento da parte dell&#8217;Utente di alcuni Dati Personali potrebbe impedire a questa Applicazione di erogare i propri servizi.<br \/>\nL&#8217;Utente si assume la responsabilit\u00e0\u00a0 dei Dati Personali di terzi pubblicati o condivisi mediante questa Applicazione e garantisce di avere il diritto di comunicarli o diffonderli, liberando il Titolare da qualsiasi responsabilit\u00e0\u00a0 verso terzi.<\/p>\n<p>Modalit\u00e0\u00a0 e luogo del trattamento dei Dati raccolti<\/p>\n<p>Modalit\u00e0\u00a0 di trattamento<br \/>\nIl Titolare tratta i Dati Personali degli Utenti adottando le opportune misure di sicurezza volte ad impedire l&#8217;accesso, la divulgazione, la modifica o la distruzione non autorizzate dei Dati Personali.<br \/>\nIl trattamento viene effettuato mediante strumenti informatici e\/o telematici, con modalit\u00e0\u00a0 organizzative e con logiche strettamente correlate alle finalit\u00e0\u00a0 indicate. Oltre al Titolare, in alcuni casi, potrebbero avere accesso ai Dati categorie di incaricati coinvolti nell&#8217;organizzazione del sito (personale amministrativo, commerciale, marketing, legali, amministratori di sistema) ovvero soggetti esterni (come fornitori di servizi tecnici terzi, corrieri postali, hosting provider, societ\u00e0\u00a0 informatiche, agenzie di comunicazione) nominati anche, se necessario, Responsabili del Trattamento da parte del Titolare. L&#8217;elenco aggiornato dei Responsabili potr\u00e0\u00a0 sempre essere richiesto al Titolare del Trattamento.<\/p>\n<p>Luogo<br \/>\nI Dati sono trattati presso le sedi operative del Titolare ed in ogni altro luogo in cui le parti coinvolte nel trattamento siano localizzate. Per ulteriori informazioni, contatta il Titolare.<\/p>\n<p>Tempi<br \/>\nI Dati sono trattati per il tempo necessario allo svolgimento del servizio richiesto dall&#8217;Utente, o richiesto dalle finalit\u00e0\u00a0 descritte in questo documento, e l&#8217;Utente pu\u00f2 sempre chiedere l&#8217;interruzione del Trattamento o la cancellazione dei Dati.<\/p>\n<p>Finalit\u00e0\u00a0 del Trattamento dei Dati raccolti<br \/>\nI Dati dell&#8217;Utente sono raccolti per consentire al Titolare di fornire i propri servizi, come per le seguenti finalit\u00e0\u00a0: Contattare l&#8217;Utente.<br \/>\nLe tipologie di Dati Personali utilizzati per ciascuna finalit\u00e0\u00a0 sono indicati nelle sezioni specifiche di questo documento.<\/p>\n<p>Dettagli sul trattamento dei Dati Personali<br \/>\nI Dati Personali sono raccolti per le seguenti finalit\u00e0\u00a0 ed utilizzando i seguenti servizi:<\/p>\n<p>Mailing List o Newsletter (Questa Applicazione)<br \/>\nCon la registrazione alla mailing list o alla newsletter, l&#8217;indirizzo email dell&#8217;Utente viene automaticamente inserito in una lista di contatti a cui potranno essere trasmessi messaggi email contenenti informazioni, anche di natura commerciale e promozionale, relative a questa Applicazione. L&#8217;indirizzo email dell&#8217;Utente potrebbe anche essere aggiunto a questa lista come risultato della registrazione a questa Applicazione o dopo aver effettuato un acquisto.<br \/>\nDati personali raccolti: Cognome, Email e Nome.<\/p>\n<p>Modulo di contatto (Questa Applicazione)<br \/>\nL&#8217;Utente, compilando con i propri Dati il modulo di contatto, acconsente al loro utilizzo per rispondere alle richieste di informazioni, di preventivo, o di qualunque altra natura indicata dall&#8217;intestazione del modulo.<br \/>\nDati personali raccolti: Cognome, Email e Nome.<\/p>\n<p>COOKIE<\/p>\n<p>garonehabitat.com (o il \u00absito\u00bb) utilizza i cookie per garantirti la migliore esperienza durante la navigazione del nostro sito.<br \/>\nGli utenti che visitano il sito utilizzeranno i cookies, ossia piccoli file salvati sul dispositivo di navigazione contenenti delle informazioni utili per migliorare l&#8217;esperienza utente e la funzionalit\u00e0\u00a0 del sito stesso. Disabilitando i cookie alcuni dei nostri servizi potrebbero non funzionare correttamente e alcune pagine non saranno visualizzate correttamente. Esistono diversi tipi di cookie, alcuni per rendere pi\u00f9 efficace l&#8217;uso del sito, altri per abilitare determinate funzionalit\u00e0\u00a0.<\/p>\n<p>COOKIE TECNICI<\/p>\n<p>Questa tipologia di cookie \u00e8 strettamente necessaria al corretto funzionamento di alcune sezioni del Sito. Sono di due categorie: persistenti e di sessione:<\/p>\n<p>persistenti: una volta chiuso il browser non vengono distrutti ma rimangono fino ad una data di scadenza preimpostata<br \/>\ndi sessione: vengono distrutti ogni volta che il browser viene chiuso<br \/>\nQuesti cookie sono necessari a visualizzare correttamente il sito e in relazione ai servizi tecnici offerti, verranno quindi sempre utilizzati e inviati, a meno che l&#8217;utenza non modifichi le impostazioni nel proprio browser in merito alla gestione dei Cookie.<\/p>\n<p>COOKIE ANALITICI<\/p>\n<p>I cookie in questa categoria vengono utilizzati per collezionare informazioni sull&#8217;uso del sito. garonehabitat.com user\u00e0\u00a0 queste informazioni in merito ad analisi statistiche anonime al fine di migliorare l&#8217;utilizzo del sito e per rendere i contenuti pi\u00f9 interessanti e attinenti ai desideri dell&#8217;utenza. Questa tipologia di cookie raccoglie dati in forma anonima sull&#8217;attivit\u00e0\u00a0 dell&#8217;utenza e su come \u00e8 arrivata sul sito. I cookie analitici sono inviati dal sito stesso o da domini di terze parti.<\/p>\n<p>COOKIE DI ANALISI DI SERVIZI DI TERZE PARTI<\/p>\n<p>Questi cookie sono utilizzati al fine di raccogliere informazioni sull&#8217;uso del sito da parte degli utenti in forma anonima quali: pagine visitate, tempo di permanenza, origini del traffico di provenienza, provenienza geografica, et\u00e0\u00a0, genere e interessi ai fini di campagne di marketing. Questi cookie sono inviati da domini di terze parti esterni al sito.<\/p>\n<p>COOKIE PER INTEGRARE PRODOTTI E FUNZIONI DI SOFTWARE DI TERZE PARTI<\/p>\n<p>Questa tipologia di cookie integra funzionalit\u00e0\u00a0 sviluppate da terzi all&#8217;interno delle pagine del sito come le icone e le preferenze espresse nei social network al fine di condivisione dei contenuti del sito o per l&#8217;uso di servizi software di terze parti (come i software per generare le mappe e ulteriori software che offrono servizi aggiuntivi). Questi cookie sono inviati da domini di terze parti e da siti partner che offrono le loro funzionalit\u00e0\u00a0 tra le pagine del Sito.<\/p>\n<p>COOKIE DI PROFILAZIONE<\/p>\n<p>Sono quei cookie necessari a creare profili utenti al fine di inviare messaggi pubblicitari in linea con le preferenze manifestate dall&#8217;utente all&#8217;interno delle pagine del sito.<\/p>\n<p>L&#8217;utente pu\u00f2 esprimere il proprio consenso all&#8217;utilizzo dei cookie con una delle seguenti modalit\u00e0\u00a0:<\/p>\n<p>Mediante specifiche configurazioni del browser utilizzato o dei relativi programmi informatici utilizzati per navigare le pagine che compongono il Sito.<br \/>\nMediante modifica delle impostazioni nell&#8217;uso dei servizi di terze parti<br \/>\nEntrambe queste soluzioni potrebbero impedire all&#8217;utente di utilizzare o visualizzare parti del Sito.<\/p>\n<p>Siti Web e servizi di terze parti<\/p>\n<p>Il sito potrebbe contenere collegamenti ad altri siti web che dispongono di una propria informativa sulla privacy, che pu\u00f2 essere diversa da quella adottata dal nostro sito, che pertanto non risponde di tali siti.<\/p>\n<p>COOKIE ADOTTATI DA QUESTO SITO<\/p>\n<p>garonehabitat.com usa Google Analytics a scopo di analisi delle visite e dell&#8217;utilizzo del sito solo ed esclusivamente per raccogliere dati relativi alla navigazione dell&#8217;utente su di esso per trarre spunti volti al miglioramento dello stesso.<\/p>\n<p>ultima modifica 7 settembre 2017<\/p>\n<\/div><\/section>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"open","template":"","meta":{"_joinchat":[],"footnotes":""},"class_list":["post-27252","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Cookie &amp; Privacy - Garone Habitat<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/garonehabitat.com\/es\/cookie-privacy\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Cookie &amp; Privacy - Garone Habitat\" \/>\n<meta property=\"og:url\" content=\"https:\/\/garonehabitat.com\/es\/cookie-privacy\/\" \/>\n<meta property=\"og:site_name\" content=\"Garone Habitat\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/GaroneHabitat\/\" \/>\n<meta property=\"article:modified_time\" content=\"2024-06-11T09:33:55+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/garonehabitat.com\/wp-content\/uploads\/2024\/06\/couple.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1100\" \/>\n\t<meta property=\"og:image:height\" content=\"863\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"6 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/garonehabitat.com\\\/es\\\/cookie-privacy\\\/\",\"url\":\"https:\\\/\\\/garonehabitat.com\\\/es\\\/cookie-privacy\\\/\",\"name\":\"Cookie & Privacy - Garone Habitat\",\"isPartOf\":{\"@id\":\"http:\\\/\\\/new.garonehabitat.com\\\/es\\\/#website\"},\"datePublished\":\"2024-05-17T12:11:50+00:00\",\"dateModified\":\"2024-06-11T09:33:55+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/garonehabitat.com\\\/es\\\/cookie-privacy\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/garonehabitat.com\\\/es\\\/cookie-privacy\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/garonehabitat.com\\\/es\\\/cookie-privacy\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/garonehabitat.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Cookie &#038; Privacy\"}]},{\"@type\":\"WebSite\",\"@id\":\"http:\\\/\\\/new.garonehabitat.com\\\/es\\\/#website\",\"url\":\"http:\\\/\\\/new.garonehabitat.com\\\/es\\\/\",\"name\":\"Garone Habitat\",\"description\":\"\",\"publisher\":{\"@id\":\"http:\\\/\\\/new.garonehabitat.com\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"http:\\\/\\\/new.garonehabitat.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"http:\\\/\\\/new.garonehabitat.com\\\/es\\\/#organization\",\"name\":\"Garone Habitat\",\"url\":\"http:\\\/\\\/new.garonehabitat.com\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"http:\\\/\\\/new.garonehabitat.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.garonehabitat.com\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/logo-white_garone-1.png\",\"contentUrl\":\"https:\\\/\\\/www.garonehabitat.com\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/logo-white_garone-1.png\",\"width\":149,\"height\":81,\"caption\":\"Garone Habitat\"},\"image\":{\"@id\":\"http:\\\/\\\/new.garonehabitat.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/GaroneHabitat\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Cookie & Privacy - Garone Habitat","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/garonehabitat.com\/es\/cookie-privacy\/","og_locale":"es_ES","og_type":"article","og_title":"Cookie & Privacy - Garone Habitat","og_url":"https:\/\/garonehabitat.com\/es\/cookie-privacy\/","og_site_name":"Garone Habitat","article_publisher":"https:\/\/www.facebook.com\/GaroneHabitat\/","article_modified_time":"2024-06-11T09:33:55+00:00","og_image":[{"width":1100,"height":863,"url":"https:\/\/garonehabitat.com\/wp-content\/uploads\/2024\/06\/couple.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Tiempo de lectura":"6 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/garonehabitat.com\/es\/cookie-privacy\/","url":"https:\/\/garonehabitat.com\/es\/cookie-privacy\/","name":"Cookie & Privacy - Garone Habitat","isPartOf":{"@id":"http:\/\/new.garonehabitat.com\/es\/#website"},"datePublished":"2024-05-17T12:11:50+00:00","dateModified":"2024-06-11T09:33:55+00:00","breadcrumb":{"@id":"https:\/\/garonehabitat.com\/es\/cookie-privacy\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/garonehabitat.com\/es\/cookie-privacy\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/garonehabitat.com\/es\/cookie-privacy\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/garonehabitat.com\/es\/"},{"@type":"ListItem","position":2,"name":"Cookie &#038; Privacy"}]},{"@type":"WebSite","@id":"http:\/\/new.garonehabitat.com\/es\/#website","url":"http:\/\/new.garonehabitat.com\/es\/","name":"Garone Habitat","description":"","publisher":{"@id":"http:\/\/new.garonehabitat.com\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"http:\/\/new.garonehabitat.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"http:\/\/new.garonehabitat.com\/es\/#organization","name":"Garone Habitat","url":"http:\/\/new.garonehabitat.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"http:\/\/new.garonehabitat.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/www.garonehabitat.com\/wp-content\/uploads\/2024\/05\/logo-white_garone-1.png","contentUrl":"https:\/\/www.garonehabitat.com\/wp-content\/uploads\/2024\/05\/logo-white_garone-1.png","width":149,"height":81,"caption":"Garone Habitat"},"image":{"@id":"http:\/\/new.garonehabitat.com\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/GaroneHabitat\/"]}]}},"_links":{"self":[{"href":"https:\/\/garonehabitat.com\/es\/wp-json\/wp\/v2\/pages\/27252","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/garonehabitat.com\/es\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/garonehabitat.com\/es\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/garonehabitat.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/garonehabitat.com\/es\/wp-json\/wp\/v2\/comments?post=27252"}],"version-history":[{"count":2,"href":"https:\/\/garonehabitat.com\/es\/wp-json\/wp\/v2\/pages\/27252\/revisions"}],"predecessor-version":[{"id":27255,"href":"https:\/\/garonehabitat.com\/es\/wp-json\/wp\/v2\/pages\/27252\/revisions\/27255"}],"wp:attachment":[{"href":"https:\/\/garonehabitat.com\/es\/wp-json\/wp\/v2\/media?parent=27252"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}