{"id":28446,"date":"2025-07-18T11:21:36","date_gmt":"2025-07-18T09:21:36","guid":{"rendered":"https:\/\/www.garonehabitat.com\/?page_id=28446"},"modified":"2025-08-01T14:28:05","modified_gmt":"2025-08-01T12:28:05","slug":"mantenimiento","status":"publish","type":"page","link":"https:\/\/garonehabitat.com\/es\/mantenimiento\/","title":{"rendered":"MANTENIMIENTO"},"content":{"rendered":"\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-16tfurz-69d195f0500528ff418b6f03c90db027\">\n.avia-section.av-16tfurz-69d195f0500528ff418b6f03c90db027 .av-extra-border-element .av-extra-border-inner{\nbackground-color:#ffffff;\n}\n<\/style>\n<div id='av_section_1'  class='avia-section av-16tfurz-69d195f0500528ff418b6f03c90db027 main_color avia-section-no-padding avia-no-border-styling  avia-builder-el-0  el_before_av_section  avia-builder-el-first  avia-bg-style-scroll av-arrow-down-section container_wrap sidebar_right'  ><div class='container av-section-cont-open' ><main  role=\"main\" itemprop=\"mainContentOfPage\"  class='template-page content  av-content-small alpha units'><div class='post-entry post-entry-type-page post-entry-28446'><div class='entry-content-wrapper clearfix'>\n\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-mb0xs295-86e7e66ed3f57b3ccda27790d4f3f0c6\">\n#top .av-special-heading.av-mb0xs295-86e7e66ed3f57b3ccda27790d4f3f0c6{\npadding-bottom:30px;\nfont-size:30px;\n}\nbody .av-special-heading.av-mb0xs295-86e7e66ed3f57b3ccda27790d4f3f0c6 .av-special-heading-tag .heading-char{\nfont-size:25px;\n}\n#top #wrap_all .av-special-heading.av-mb0xs295-86e7e66ed3f57b3ccda27790d4f3f0c6 .av-special-heading-tag{\nfont-size:30px;\npadding:50px 0 0 0;\n}\n.av-special-heading.av-mb0xs295-86e7e66ed3f57b3ccda27790d4f3f0c6 .av-subheading{\nfont-size:15px;\n}\n\n@media only screen and (min-width: 480px) and (max-width: 767px){ \n#top #wrap_all .av-special-heading.av-mb0xs295-86e7e66ed3f57b3ccda27790d4f3f0c6 .av-special-heading-tag{\nfont-size:0.8em;\n}\n}\n\n@media only screen and (max-width: 479px){ \n#top #wrap_all .av-special-heading.av-mb0xs295-86e7e66ed3f57b3ccda27790d4f3f0c6 .av-special-heading-tag{\nfont-size:0.8em;\n}\n}\n<\/style>\n<div  class='av-special-heading av-mb0xs295-86e7e66ed3f57b3ccda27790d4f3f0c6 av-special-heading-h1 blockquote elegant-quote elegant-centered  avia-builder-el-1  avia-builder-el-no-sibling  av-inherit-size'><h1 class='av-special-heading-tag'  itemprop=\"headline\"  ><span class=\"heading-wrap\">MANTENIMIENTO DE MARCOS DE VENTANAS<\/span><\/h1><div class=\"special-heading-border\"><div class=\"special-heading-inner-border\"><\/div><\/div><\/div>\n\n<\/div><\/div><\/main><!-- close content main element --><\/div><div class='av-extra-border-element border-extra-arrow-down'><div class='av-extra-border-outer'><div class='av-extra-border-inner'><\/div><\/div><\/div><\/div>\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-2j87gv-71f974baa70fa7584b6fd18ae67d8ec4\">\n.avia-section.av-2j87gv-71f974baa70fa7584b6fd18ae67d8ec4{\nbackground-color:#f8f8f8;\nbackground-image:unset;\n}\n<\/style>\n<div id='av_section_2'  class='avia-section av-2j87gv-71f974baa70fa7584b6fd18ae67d8ec4 main_color avia-section-default avia-no-border-styling  avia-builder-el-2  el_after_av_section  el_before_av_button  avia-bg-style-scroll container_wrap sidebar_right'  ><div class='container av-section-cont-open' ><div class='template-page content  av-content-small alpha units'><div class='post-entry post-entry-type-page post-entry-28446'><div class='entry-content-wrapper clearfix'>\n\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-mb0xsrei-c5603f7e2b22ca0a8ace7af60d412c5c\">\n#top .av_textblock_section.av-mb0xsrei-c5603f7e2b22ca0a8ace7af60d412c5c .avia_textblock{\ncolor:#000000;\n}\n<\/style>\n<section  class='av_textblock_section av-mb0xsrei-c5603f7e2b22ca0a8ace7af60d412c5c '   itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/CreativeWork\" ><div class='avia_textblock av_inherit_color'  itemprop=\"text\" ><p>El mantenimiento de ventanas y puertas es esencial para conservar su eficiencia y belleza a lo largo del tiempo. <strong>Garone Habitat<\/strong> ofrece instrucciones detalladas para el cuidado de sus ventanas y puertas, incluyendo ventanas con diversos tipos de apertura, como abatibles, oscilobatientes, pivotantes, oscilo-correderas y elevables-correderas.<\/p>\n<h2><strong>Mantenimiento rutinario: Mecanismos y juntas<\/strong><\/h2>\n<div><\/div>\n<div>\n<p>Para garantizar el correcto funcionamiento de sus ventanas y puertas, recomendamos realizar un mantenimiento semestral y anual:<\/p>\n<ul>\n<li><strong>Limpieza<\/strong>: Cada seis meses, limpie las partes m\u00f3viles y de cierre de los mecanismos y las juntas con un pa\u00f1o suave. Es importante evitar el contacto directo de los mecanismos con la humedad y los detergentes. Las juntas nunca deben entrar en contacto con detergentes \u00e1cidos.<\/li>\n<li><strong>Revitalizaci\u00f3n de juntas<\/strong>: Utilice productos espec\u00edficos para el cuidado de las juntas de los autom\u00f3viles, como aceite de vaselina o espray de silicona, para mantenerlas el\u00e1sticas y funcionales.<\/li>\n<li><strong>Engrase<\/strong>: Lubrique todas las piezas m\u00f3viles y de cierre de los mecanismos de herrajes con un lubricante espec\u00edfico al menos una vez al a\u00f1o.<\/li>\n<\/ul>\n<\/div>\n<h2><strong>Ajustes y comprobaciones peri\u00f3dicas<\/strong><\/h2>\n<ul>\n<li><strong>Ajustes:<\/strong> Los ajustes de los mecanismos, incluyendo la presi\u00f3n de la puerta sobre el marco y la alineaci\u00f3n, deben ser realizados por personal especializado. En el caso de ventanas oscilobatientes, en caso de una falsa apertura, coloque la esquina superior de la hoja contra el marco, presione el mecanismo de elevaci\u00f3n de la hoja, mueva la manilla a la posici\u00f3n de apertura con bisagras y luego suelte el mecanismo.<\/li>\n<li><strong>Inspecciones<\/strong>: Cada seis meses, revise el estado de las bisagras, la cremona y las piezas de seguridad para detectar desgaste. Revise anualmente los sellos para detectar desgaste, cortes o endurecimientos que puedan comprometer su sellado; si es necesario, reempl\u00e1celos tras consultar con los t\u00e9cnicos de Garone Habitat.<\/li>\n<\/ul>\n<h2><strong>Protecci\u00f3n de la madera y la pel\u00edcula de pintura<\/strong><\/h2>\n<p>La madera es un material biol\u00f3gico que requiere un cuidado especial, especialmente cuando se expone a la intemperie. Factores como los rayos UV, la humedad y las altas temperaturas pueden deteriorar la pintura y la propia madera. Los hongos tambi\u00e9n pueden da\u00f1ar la madera si la humedad supera el 20 % y no se protege con biocidas.<\/p>\n<ul>\n<li><strong>Inspecci\u00f3n de la pel\u00edcula de pintura<\/strong>: Inspeccione la superficie cada seis meses para asegurarse de que la capa de pintura no est\u00e9 opaca, delgada ni agrietada. Preste especial atenci\u00f3n a la veta final de las jambas de las ventanas, una zona cr\u00edtica para la absorci\u00f3n de humedad.<\/li>\n<li><strong>Limpieza<\/strong>: Limpie la superficie con un detergente l\u00edquido neutro suave para eliminar el smog y las part\u00edculas que pueden da\u00f1ar la pintura.<\/li>\n<li><strong>Productos de limpieza recomendados<\/strong>: Recomendamos aplicar T.Clean y T.Top+ Renner al menos dos veces al a\u00f1o, en primavera y oto\u00f1o, para restaurar el brillo de la pintura. Estos productos tambi\u00e9n se pueden usar en vidrio.<strong>Productos que se deben evitar<\/strong>: No utilice limpiadores comerciales agresivos, disolventes qu\u00edmicos (alcohol, acetona) ni sustancias como lej\u00eda y amon\u00edaco, ya que pueden da\u00f1ar la pel\u00edcula protectora.<\/li>\n<\/ul>\n<\/div><\/section>\n<div  class='avia-video av-md8mbbqr-eb54982c5b8b6a823550b53afd1ed146 avia-video-16-9 av-no-preview-image avia-video-load-always av-lazyload-immediate av-lazyload-video-embed'  itemprop=\"video\" itemtype=\"https:\/\/schema.org\/VideoObject\"  data-original_url='https:\/\/www.youtube.com\/watch?v=QFxTCBsRB2M&amp;ab_channel=GARONEHABITAT'><script type='text\/html' class='av-video-tmpl'><div class='avia-iframe-wrap'><iframe loading=\"lazy\" title=\"Come prendersi cura dei serramenti con i prodotti Renner\" width=\"1500\" height=\"844\" src=\"https:\/\/www.youtube.com\/embed\/QFxTCBsRB2M?feature=oembed&enablejsapi=1&origin=https:\/\/www.garonehabitat.com&autoplay=0&loop=0&controls=1&mute=0\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe><\/div><\/script><div class='av-click-to-play-overlay'><div class=\"avia_playpause_icon\"><\/div><\/div><\/div>\n\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-md8m9o4j-68175d9582a0fbda93a565e56c3c0e34\">\n#top .av_textblock_section.av-md8m9o4j-68175d9582a0fbda93a565e56c3c0e34 .avia_textblock{\ncolor:#000000;\n}\n<\/style>\n<section  class='av_textblock_section av-md8m9o4j-68175d9582a0fbda93a565e56c3c0e34 '   itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/CreativeWork\" ><div class='avia_textblock av_inherit_color'  itemprop=\"text\" ><h2><strong>Renovaci\u00f3n de la capa de pintura<\/strong><\/h2>\n<div><\/div>\n<div>\n<p>Si se ha descuidado el mantenimiento rutinario y la capa de pintura se ha desprendido, rayado, agrietado o ha sufrido filtraciones de agua, es necesario renovarla:<\/p>\n<ul>\n<li>Lije el marco con papel de lija de grano 150 y limpie bien la superficie.<\/li>\n<li>Aplique el tinte al agua del color original con una brocha en las zonas aclaradas y deje secar durante unas 8 horas.<\/li>\n<li>Lije uniformemente con una esponja abrasiva, elimine cualquier residuo y aplique una o dos capas de acabado transparente al agua con una brocha. Cubra las superficies de vidrio con hojas de papel y cinta adhesiva.<\/li>\n<\/ul>\n<p>Espere de 6 a 8 horas para aplicar una segunda capa o volver a montar el marco.<\/p>\n<p>Deje secar de 24 a 36 horas antes de cerrar puertas y ventanas para evitar que la pintura se pegue. Guarde la pintura en un lugar fresco y protegido de las heladas.<\/p>\n<p><strong style=\"font-size: 28px;\"><strong>Protecci\u00f3n del aluminio<\/strong><\/strong><\/p>\n<\/div>\n<p>Se recomienda el uso de estructuras con exterior de aluminio (madera-aluminio) para reducir el mantenimiento en zonas con alto contenido de sal o contaminaci\u00f3n atmosf\u00e9rica.<\/p>\n<ul>\n<li><strong>Limpieza del exterior de aluminio:<\/strong> Limpie a fondo el exterior de aluminio al menos dos veces al a\u00f1o con agua tibia y jab\u00f3n neutro, frotando con un pa\u00f1o suave. Se pueden usar limpiadores a vapor a una distancia m\u00ednima de 40 cm en climas templados.<\/li>\n<li><strong>Precauciones:<\/strong> No utilice limpiadores abrasivos, a base de amon\u00edaco o cloro (como lej\u00eda). Evite limpiar superficies expuestas directamente a fuentes de calor o luz solar. En entornos agresivos (zonas costeras, zonas contaminadas), limpie con mayor frecuencia.<\/li>\n<\/ul>\n<p><strong>Tratamientos espec\u00edficos<\/strong>: Los perfiles de aluminio <strong>Garone Habitat<\/strong> se someten a un pretratamiento llamado SEASIDE para aumentar la resistencia a la corrosi\u00f3n, especialmente indicado para entornos marinos o con alta contaminaci\u00f3n. Sin embargo, este tratamiento por s\u00ed solo no garantiza la ausencia total de corrosi\u00f3n filiforme, que puede originarse en zonas desprotegidas de la extrusi\u00f3n.<\/p>\n<h2><strong>Consejos adicionales<\/strong><\/h2>\n<ul>\n<li>Proteja las zonas de corte de la extrusi\u00f3n durante el montaje.<\/li>\n<li>Minimice la formaci\u00f3n de acoplamientos galv\u00e1nicos entre metales diferentes en las juntas.<\/li>\n<li>Evite geometr\u00edas que creen trampas de corrosi\u00f3n (humedad o zonas mal ventiladas) y garantice la accesibilidad para la limpieza.<\/li>\n<\/ul>\n<p>Despu\u00e9s de limpiar los perfiles de aluminio, puede tratar la superficie con ceras transparentes para autom\u00f3viles para mantener su brillo, evitando acabados mate, colores arrugados, luz solar directa y temperaturas superiores a 25 \u00b0C.<\/p>\n<ul>\n<li>Proteja adecuadamente las superficies pintadas durante el almacenamiento, el montaje y la instalaci\u00f3n.<\/li>\n<li>Drenaje de agua<\/li>\n<\/ul>\n<p>La capacidad de los marcos de ventanas y puertas para evitar la penetraci\u00f3n de agua es crucial para un entorno saludable. Esto depende de:<\/p>\n<ul>\n<li>El estado de desgaste de las juntas.<\/li>\n<li>El ajuste del marco de la ventana.<\/li>\n<li>La limpieza de los bordes de goteo para eliminar residuos que puedan impedir el flujo de agua.<\/li>\n<\/ul>\n<h2><strong>Mantenimiento extraordinario<\/strong><\/h2>\n<p>Todos los trabajos de mantenimiento extraordinario, como la sustituci\u00f3n de cristales rotos o el desmontaje y montaje de los marcos de las ventanas, deben ser realizados exclusivamente por personal especializado. <strong>Garone Habitat<\/strong> est\u00e1 a su disposici\u00f3n para cualquier necesidad que vaya m\u00e1s all\u00e1 del mantenimiento ordinario.<\/p>\n<\/div><\/section>\n<\/div><\/div><\/div><!-- close content main div --><\/div><\/div><div id='after_section_2'  class='main_color av_default_container_wrap container_wrap sidebar_right'  ><div class='container av-section-cont-open' ><div class='template-page content  av-content-small alpha units'><div class='post-entry post-entry-type-page post-entry-28446'><div class='entry-content-wrapper clearfix'>\n<div  class='avia-button-wrap av-mdssugcf-860a55a4f269e25c8bf229ea20f7b916-wrap avia-button-center  avia-builder-el-6  el_after_av_section  avia-builder-el-no-sibling '><a href=\"\/wp-content\/uploads\/2025\/08\/Libretto-uso-e-manutenzione-Garone.pdf\" class=\"avia-button av-mdssugcf-860a55a4f269e25c8bf229ea20f7b916 av-link-btn avia-icon_select-no avia-size-small avia-position-center avia-color-theme-color\" target=\"_blank\" rel=\"noopener noreferrer\"><span class='avia_iconbox_title' >DESCARGUE EL FOLLETO DE MANTENIMIENTO COMPLETO<\/span><\/a><\/div>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_joinchat":[],"footnotes":""},"class_list":["post-28446","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>MANTENIMIENTO - Garone Habitat<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/garonehabitat.com\/es\/mantenimiento\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"MANTENIMIENTO - Garone Habitat\" \/>\n<meta property=\"og:url\" content=\"https:\/\/garonehabitat.com\/es\/mantenimiento\/\" \/>\n<meta property=\"og:site_name\" content=\"Garone Habitat\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/GaroneHabitat\/\" \/>\n<meta property=\"article:modified_time\" content=\"2025-08-01T12:28:05+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/garonehabitat.com\/wp-content\/uploads\/2024\/06\/couple.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1100\" \/>\n\t<meta property=\"og:image:height\" content=\"863\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"5 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/garonehabitat.com\\\/es\\\/mantenimiento\\\/\",\"url\":\"https:\\\/\\\/garonehabitat.com\\\/es\\\/mantenimiento\\\/\",\"name\":\"MANTENIMIENTO - Garone Habitat\",\"isPartOf\":{\"@id\":\"http:\\\/\\\/new.garonehabitat.com\\\/es\\\/#website\"},\"datePublished\":\"2025-07-18T09:21:36+00:00\",\"dateModified\":\"2025-08-01T12:28:05+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/garonehabitat.com\\\/es\\\/mantenimiento\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/garonehabitat.com\\\/es\\\/mantenimiento\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/garonehabitat.com\\\/es\\\/mantenimiento\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/garonehabitat.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"MANTENIMIENTO\"}]},{\"@type\":\"WebSite\",\"@id\":\"http:\\\/\\\/new.garonehabitat.com\\\/es\\\/#website\",\"url\":\"http:\\\/\\\/new.garonehabitat.com\\\/es\\\/\",\"name\":\"Garone Habitat\",\"description\":\"\",\"publisher\":{\"@id\":\"http:\\\/\\\/new.garonehabitat.com\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"http:\\\/\\\/new.garonehabitat.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"http:\\\/\\\/new.garonehabitat.com\\\/es\\\/#organization\",\"name\":\"Garone Habitat\",\"url\":\"http:\\\/\\\/new.garonehabitat.com\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"http:\\\/\\\/new.garonehabitat.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.garonehabitat.com\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/logo-white_garone-1.png\",\"contentUrl\":\"https:\\\/\\\/www.garonehabitat.com\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/logo-white_garone-1.png\",\"width\":149,\"height\":81,\"caption\":\"Garone Habitat\"},\"image\":{\"@id\":\"http:\\\/\\\/new.garonehabitat.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/GaroneHabitat\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"MANTENIMIENTO - Garone Habitat","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/garonehabitat.com\/es\/mantenimiento\/","og_locale":"es_ES","og_type":"article","og_title":"MANTENIMIENTO - Garone Habitat","og_url":"https:\/\/garonehabitat.com\/es\/mantenimiento\/","og_site_name":"Garone Habitat","article_publisher":"https:\/\/www.facebook.com\/GaroneHabitat\/","article_modified_time":"2025-08-01T12:28:05+00:00","og_image":[{"width":1100,"height":863,"url":"https:\/\/garonehabitat.com\/wp-content\/uploads\/2024\/06\/couple.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Tiempo de lectura":"5 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/garonehabitat.com\/es\/mantenimiento\/","url":"https:\/\/garonehabitat.com\/es\/mantenimiento\/","name":"MANTENIMIENTO - Garone Habitat","isPartOf":{"@id":"http:\/\/new.garonehabitat.com\/es\/#website"},"datePublished":"2025-07-18T09:21:36+00:00","dateModified":"2025-08-01T12:28:05+00:00","breadcrumb":{"@id":"https:\/\/garonehabitat.com\/es\/mantenimiento\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/garonehabitat.com\/es\/mantenimiento\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/garonehabitat.com\/es\/mantenimiento\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/garonehabitat.com\/es\/"},{"@type":"ListItem","position":2,"name":"MANTENIMIENTO"}]},{"@type":"WebSite","@id":"http:\/\/new.garonehabitat.com\/es\/#website","url":"http:\/\/new.garonehabitat.com\/es\/","name":"Garone Habitat","description":"","publisher":{"@id":"http:\/\/new.garonehabitat.com\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"http:\/\/new.garonehabitat.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"http:\/\/new.garonehabitat.com\/es\/#organization","name":"Garone Habitat","url":"http:\/\/new.garonehabitat.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"http:\/\/new.garonehabitat.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/www.garonehabitat.com\/wp-content\/uploads\/2024\/05\/logo-white_garone-1.png","contentUrl":"https:\/\/www.garonehabitat.com\/wp-content\/uploads\/2024\/05\/logo-white_garone-1.png","width":149,"height":81,"caption":"Garone Habitat"},"image":{"@id":"http:\/\/new.garonehabitat.com\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/GaroneHabitat\/"]}]}},"_links":{"self":[{"href":"https:\/\/garonehabitat.com\/es\/wp-json\/wp\/v2\/pages\/28446","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/garonehabitat.com\/es\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/garonehabitat.com\/es\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/garonehabitat.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/garonehabitat.com\/es\/wp-json\/wp\/v2\/comments?post=28446"}],"version-history":[{"count":3,"href":"https:\/\/garonehabitat.com\/es\/wp-json\/wp\/v2\/pages\/28446\/revisions"}],"predecessor-version":[{"id":28461,"href":"https:\/\/garonehabitat.com\/es\/wp-json\/wp\/v2\/pages\/28446\/revisions\/28461"}],"wp:attachment":[{"href":"https:\/\/garonehabitat.com\/es\/wp-json\/wp\/v2\/media?parent=28446"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}