{"id":27769,"date":"2024-10-21T17:21:14","date_gmt":"2024-10-21T15:21:14","guid":{"rendered":"https:\/\/www.garonehabitat.com\/?p=27769"},"modified":"2024-10-21T17:21:14","modified_gmt":"2024-10-21T15:21:14","slug":"garone-vittoria-awards-serramento","status":"publish","type":"post","link":"https:\/\/garonehabitat.com\/es\/garone-vittoria-awards-serramento\/","title":{"rendered":"Garone Habitat trionfa agli Awards del Serramento 2024 con Linfa"},"content":{"rendered":"<p><span style=\"font-weight: 400;\">Grande successo per Garone Habitat agli <\/span><b>Awards del Serramento 2024<\/b><span style=\"font-weight: 400;\">. L\u2019azienda salernitana ha trionfato nella categoria \u201cLegno\u201d grazie all\u2019innovativo infisso <\/span><a href=\"https:\/\/www.garonehabitat.com\/linfa-infissi-legno\/\"><b>Linfa<\/b><\/a><span style=\"font-weight: 400;\">, parte della linea \u201c<\/span><i><span style=\"font-weight: 400;\">Radici<\/span><\/i><span style=\"font-weight: 400;\">\u201d, confermandosi leader nel settore. Questo prestigioso riconoscimento, assegnato dai lettori del sito <a href=\"https:\/\/www.guidafinestra.it\/\">guidafinestra.it<\/a> e da una giuria di esperti, \u00e8 stato consegnato il 17 ottobre 2024 durante la cerimonia di premiazione tenutasi presso l\u2019Hotel Parco dei Principi di Bari, in occasione del <\/span><i><span style=\"font-weight: 400;\">\u201c<\/span><\/i><b><i>Forum Serramenti&amp;Vetro<\/i><\/b><i><span style=\"font-weight: 400;\">\u201d<\/span><\/i><span style=\"font-weight: 400;\">. L\u2019evento ha riunito i principali attori del settore, offrendo un\u2019importante piattaforma di discussione per le novit\u00e0 e le innovazioni del mondo dei serramenti.\u00a0<\/span><\/p>\n<h2><b>Gli Awards del Serramento<\/b><\/h2>\n<p><span style=\"font-weight: 400;\">Gli Awards del Serramento sono uno dei premi pi\u00f9 ambiti nel mondo dei serramenti e del vetro, volti a riconoscere i migliori prodotti innovativi del settore. Il premio \u00e8 diventato un punto di riferimento per produttori, serramentisti, tecnici e vetrai. Questo riconoscimento certifica l\u2019eccellenza di un prodotto in termini di qualit\u00e0, innovazione, prestazioni tecniche e design. Nell\u2019edizione 2024, la vittoria di Garone Habitat con Linfa rappresenta un traguardo significativo, sottolineando la capacit\u00e0 dell\u2019azienda di combinare tradizione e tecnologia in un prodotto innovativo.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Linfa \u00e8 un infisso che fonde tradizione e innovazione, offrendo una soluzione in legno completamente personalizzabile sia dal punto di vista estetico che tecnico. Questa finestra si distingue per la sua versatilit\u00e0, resa possibile grazie alla cover esterna intercambiabile, una caratteristica brevettata che consente di cambiare facilmente l\u2019aspetto esteriore del serramento. La cover pu\u00f2 essere rimossa con una semplice chiave a brugola, permettendo di scegliere tra una vasta gamma di colori, finiture ed essenze.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Queste caratteristiche sono state dei fattori chiave per il riconoscimento del premio, in quanto consente di trasformare ogni ambiente in uno spazio unico e personalizzato.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Linfa non \u00e8 solo un prodotto esteticamente accattivante, ma anche estremamente funzionale. Grazie alle sue elevate prestazioni in termini di isolamento termico e acustico, garantisce un\u2019ottima efficienza energetica, riducendo al minimo le dispersioni di calore. Inoltre, offre standard di sicurezza elevati, assicurando tranquillit\u00e0 e comfort a chi lo sceglie per la propria casa o attivit\u00e0.<\/span><\/p>\n<h2><b>Un traguardo importante per Garone Habitat<\/b><\/h2>\n<p><span style=\"font-weight: 400;\">La vittoria di Linfa agli Awards del Serramento 2024 rappresenta non solo un riconoscimento del valore del prodotto, ma anche un importante traguardo per Garone Habitat, che continua a innovare nel settore dei serramenti con soluzioni all\u2019avanguardia.\u00a0<\/span><\/p>\n<p><i><span style=\"font-weight: 400;\">\u201cLinfa rappresenta una vera e propria rivoluzione nel mondo dei serramenti in legno <\/span><\/i><span style=\"font-weight: 400;\">\u2013 dichiara <\/span><b>Pasquale Garone<\/b><span style=\"font-weight: 400;\">, Direttore Commerciale di Garone Habitat \u2013<\/span><i><span style=\"font-weight: 400;\"> La sua cover esterna intercambiabile non solo offre infinite possibilit\u00e0 di personalizzazione, ma \u00e8 anche un esempio di come il design possa coniugarsi con la funzionalit\u00e0.<\/span><\/i><span style=\"font-weight: 400;\"> S<\/span><i><span style=\"font-weight: 400;\">iamo entusiasti di aver intrapreso questo viaggio e di aver ottenuto un riconoscimento cos\u00ec prestigioso\u201d<\/span><\/i><span style=\"font-weight: 400;\">.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Il successo ottenuto testimonia l\u2019impegno dell\u2019azienda nel proporre prodotti che coniugano qualit\u00e0, estetica e funzionalit\u00e0, rispondendo alle esigenze di un mercato in continua evoluzione. Garone Habitat si conferma cos\u00ec un punto di riferimento nel settore, pronta a dettare le tendenze future.<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Grande successo per Garone Habitat agli Awards del Serramento 2024. L\u2019azienda salernitana ha trionfato nella categoria \u201cLegno\u201d grazie all\u2019innovativo infisso Linfa, parte della linea \u201cRadici\u201d, confermandosi leader nel settore. Questo prestigioso riconoscimento, assegnato dai lettori del sito guidafinestra.it e da una giuria di esperti, \u00e8 stato consegnato il 17 ottobre 2024 durante la cerimonia di [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":27771,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_joinchat":[],"footnotes":""},"categories":[2],"tags":[92,95,91,90,36],"class_list":["post-27769","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-news","tag-awards-del-serramento","tag-infissi-in-legno","tag-linfa","tag-radici","tag-serramenti"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Garone Habitat trionfa agli Awards del Serramento 2024 con Linfa - Garone Habitat<\/title>\n<meta name=\"description\" content=\"Trionfo di Garone Habitat agli Awards del Serramento 2024: premiati gli infissi &quot;Linfa&quot; della linea &quot;Radici&quot;.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/garonehabitat.com\/es\/garone-vittoria-awards-serramento\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Garone Habitat trionfa agli Awards del Serramento 2024 con Linfa - Garone Habitat\" \/>\n<meta property=\"og:description\" content=\"Trionfo di Garone Habitat agli Awards del Serramento 2024: premiati gli infissi &quot;Linfa&quot; della linea &quot;Radici&quot;.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/garonehabitat.com\/es\/garone-vittoria-awards-serramento\/\" \/>\n<meta property=\"og:site_name\" content=\"Garone Habitat\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/GaroneHabitat\/\" \/>\n<meta property=\"article:published_time\" content=\"2024-10-21T15:21:14+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/garonehabitat.com\/wp-content\/uploads\/2024\/10\/awards-del-serramento-2024.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"588\" \/>\n\t<meta property=\"og:image:height\" content=\"378\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"mtncompany\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"mtncompany\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/garonehabitat.com\\\/es\\\/garone-vittoria-awards-serramento\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/garonehabitat.com\\\/es\\\/garone-vittoria-awards-serramento\\\/\"},\"author\":{\"name\":\"mtncompany\",\"@id\":\"http:\\\/\\\/new.garonehabitat.com\\\/es\\\/#\\\/schema\\\/person\\\/d446bb2eccc913cfb01e8a4b83c0b2a5\"},\"headline\":\"Garone Habitat trionfa agli Awards del Serramento 2024 con Linfa\",\"datePublished\":\"2024-10-21T15:21:14+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/garonehabitat.com\\\/es\\\/garone-vittoria-awards-serramento\\\/\"},\"wordCount\":494,\"commentCount\":0,\"publisher\":{\"@id\":\"http:\\\/\\\/new.garonehabitat.com\\\/es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/garonehabitat.com\\\/es\\\/garone-vittoria-awards-serramento\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/garonehabitat.com\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/awards-del-serramento-2024.jpg\",\"keywords\":[\"Awards del Serramento\",\"infissi in legno\",\"Linfa\",\"radici\",\"serramenti\"],\"articleSection\":[\"News\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/garonehabitat.com\\\/es\\\/garone-vittoria-awards-serramento\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/garonehabitat.com\\\/es\\\/garone-vittoria-awards-serramento\\\/\",\"url\":\"https:\\\/\\\/garonehabitat.com\\\/es\\\/garone-vittoria-awards-serramento\\\/\",\"name\":\"Garone Habitat trionfa agli Awards del Serramento 2024 con Linfa - Garone Habitat\",\"isPartOf\":{\"@id\":\"http:\\\/\\\/new.garonehabitat.com\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/garonehabitat.com\\\/es\\\/garone-vittoria-awards-serramento\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/garonehabitat.com\\\/es\\\/garone-vittoria-awards-serramento\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/garonehabitat.com\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/awards-del-serramento-2024.jpg\",\"datePublished\":\"2024-10-21T15:21:14+00:00\",\"description\":\"Trionfo di Garone Habitat agli Awards del Serramento 2024: premiati gli infissi \\\"Linfa\\\" della linea \\\"Radici\\\".\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/garonehabitat.com\\\/es\\\/garone-vittoria-awards-serramento\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/garonehabitat.com\\\/es\\\/garone-vittoria-awards-serramento\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/garonehabitat.com\\\/es\\\/garone-vittoria-awards-serramento\\\/#primaryimage\",\"url\":\"https:\\\/\\\/garonehabitat.com\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/awards-del-serramento-2024.jpg\",\"contentUrl\":\"https:\\\/\\\/garonehabitat.com\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/awards-del-serramento-2024.jpg\",\"width\":588,\"height\":378,\"caption\":\"awards del serramento 2024\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/garonehabitat.com\\\/es\\\/garone-vittoria-awards-serramento\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/garonehabitat.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Garone Habitat trionfa agli Awards del Serramento 2024 con Linfa\"}]},{\"@type\":\"WebSite\",\"@id\":\"http:\\\/\\\/new.garonehabitat.com\\\/es\\\/#website\",\"url\":\"http:\\\/\\\/new.garonehabitat.com\\\/es\\\/\",\"name\":\"Garone Habitat\",\"description\":\"\",\"publisher\":{\"@id\":\"http:\\\/\\\/new.garonehabitat.com\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"http:\\\/\\\/new.garonehabitat.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"http:\\\/\\\/new.garonehabitat.com\\\/es\\\/#organization\",\"name\":\"Garone Habitat\",\"url\":\"http:\\\/\\\/new.garonehabitat.com\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"http:\\\/\\\/new.garonehabitat.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.garonehabitat.com\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/logo-white_garone-1.png\",\"contentUrl\":\"https:\\\/\\\/www.garonehabitat.com\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/logo-white_garone-1.png\",\"width\":149,\"height\":81,\"caption\":\"Garone Habitat\"},\"image\":{\"@id\":\"http:\\\/\\\/new.garonehabitat.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/GaroneHabitat\\\/\"]},{\"@type\":\"Person\",\"@id\":\"http:\\\/\\\/new.garonehabitat.com\\\/es\\\/#\\\/schema\\\/person\\\/d446bb2eccc913cfb01e8a4b83c0b2a5\",\"name\":\"mtncompany\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/6f6ea4fec6e1e80edb7a6d37e40c0fba16e8bae2f5468cc40200f47433e0d644?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/6f6ea4fec6e1e80edb7a6d37e40c0fba16e8bae2f5468cc40200f47433e0d644?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/6f6ea4fec6e1e80edb7a6d37e40c0fba16e8bae2f5468cc40200f47433e0d644?s=96&d=mm&r=g\",\"caption\":\"mtncompany\"},\"sameAs\":[\"https:\\\/\\\/www.garonehabitat.com\"],\"url\":\"https:\\\/\\\/garonehabitat.com\\\/es\\\/author\\\/mtncompany\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Garone Habitat trionfa agli Awards del Serramento 2024 con Linfa - Garone Habitat","description":"Trionfo di Garone Habitat agli Awards del Serramento 2024: premiati gli infissi \"Linfa\" della linea \"Radici\".","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/garonehabitat.com\/es\/garone-vittoria-awards-serramento\/","og_locale":"es_ES","og_type":"article","og_title":"Garone Habitat trionfa agli Awards del Serramento 2024 con Linfa - Garone Habitat","og_description":"Trionfo di Garone Habitat agli Awards del Serramento 2024: premiati gli infissi \"Linfa\" della linea \"Radici\".","og_url":"https:\/\/garonehabitat.com\/es\/garone-vittoria-awards-serramento\/","og_site_name":"Garone Habitat","article_publisher":"https:\/\/www.facebook.com\/GaroneHabitat\/","article_published_time":"2024-10-21T15:21:14+00:00","og_image":[{"width":588,"height":378,"url":"https:\/\/garonehabitat.com\/wp-content\/uploads\/2024\/10\/awards-del-serramento-2024.jpg","type":"image\/jpeg"}],"author":"mtncompany","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"mtncompany","Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/garonehabitat.com\/es\/garone-vittoria-awards-serramento\/#article","isPartOf":{"@id":"https:\/\/garonehabitat.com\/es\/garone-vittoria-awards-serramento\/"},"author":{"name":"mtncompany","@id":"http:\/\/new.garonehabitat.com\/es\/#\/schema\/person\/d446bb2eccc913cfb01e8a4b83c0b2a5"},"headline":"Garone Habitat trionfa agli Awards del Serramento 2024 con Linfa","datePublished":"2024-10-21T15:21:14+00:00","mainEntityOfPage":{"@id":"https:\/\/garonehabitat.com\/es\/garone-vittoria-awards-serramento\/"},"wordCount":494,"commentCount":0,"publisher":{"@id":"http:\/\/new.garonehabitat.com\/es\/#organization"},"image":{"@id":"https:\/\/garonehabitat.com\/es\/garone-vittoria-awards-serramento\/#primaryimage"},"thumbnailUrl":"https:\/\/garonehabitat.com\/wp-content\/uploads\/2024\/10\/awards-del-serramento-2024.jpg","keywords":["Awards del Serramento","infissi in legno","Linfa","radici","serramenti"],"articleSection":["News"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/garonehabitat.com\/es\/garone-vittoria-awards-serramento\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/garonehabitat.com\/es\/garone-vittoria-awards-serramento\/","url":"https:\/\/garonehabitat.com\/es\/garone-vittoria-awards-serramento\/","name":"Garone Habitat trionfa agli Awards del Serramento 2024 con Linfa - Garone Habitat","isPartOf":{"@id":"http:\/\/new.garonehabitat.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/garonehabitat.com\/es\/garone-vittoria-awards-serramento\/#primaryimage"},"image":{"@id":"https:\/\/garonehabitat.com\/es\/garone-vittoria-awards-serramento\/#primaryimage"},"thumbnailUrl":"https:\/\/garonehabitat.com\/wp-content\/uploads\/2024\/10\/awards-del-serramento-2024.jpg","datePublished":"2024-10-21T15:21:14+00:00","description":"Trionfo di Garone Habitat agli Awards del Serramento 2024: premiati gli infissi \"Linfa\" della linea \"Radici\".","breadcrumb":{"@id":"https:\/\/garonehabitat.com\/es\/garone-vittoria-awards-serramento\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/garonehabitat.com\/es\/garone-vittoria-awards-serramento\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/garonehabitat.com\/es\/garone-vittoria-awards-serramento\/#primaryimage","url":"https:\/\/garonehabitat.com\/wp-content\/uploads\/2024\/10\/awards-del-serramento-2024.jpg","contentUrl":"https:\/\/garonehabitat.com\/wp-content\/uploads\/2024\/10\/awards-del-serramento-2024.jpg","width":588,"height":378,"caption":"awards del serramento 2024"},{"@type":"BreadcrumbList","@id":"https:\/\/garonehabitat.com\/es\/garone-vittoria-awards-serramento\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/garonehabitat.com\/es\/"},{"@type":"ListItem","position":2,"name":"Garone Habitat trionfa agli Awards del Serramento 2024 con Linfa"}]},{"@type":"WebSite","@id":"http:\/\/new.garonehabitat.com\/es\/#website","url":"http:\/\/new.garonehabitat.com\/es\/","name":"Garone Habitat","description":"","publisher":{"@id":"http:\/\/new.garonehabitat.com\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"http:\/\/new.garonehabitat.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"http:\/\/new.garonehabitat.com\/es\/#organization","name":"Garone Habitat","url":"http:\/\/new.garonehabitat.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"http:\/\/new.garonehabitat.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/www.garonehabitat.com\/wp-content\/uploads\/2024\/05\/logo-white_garone-1.png","contentUrl":"https:\/\/www.garonehabitat.com\/wp-content\/uploads\/2024\/05\/logo-white_garone-1.png","width":149,"height":81,"caption":"Garone Habitat"},"image":{"@id":"http:\/\/new.garonehabitat.com\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/GaroneHabitat\/"]},{"@type":"Person","@id":"http:\/\/new.garonehabitat.com\/es\/#\/schema\/person\/d446bb2eccc913cfb01e8a4b83c0b2a5","name":"mtncompany","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/6f6ea4fec6e1e80edb7a6d37e40c0fba16e8bae2f5468cc40200f47433e0d644?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/6f6ea4fec6e1e80edb7a6d37e40c0fba16e8bae2f5468cc40200f47433e0d644?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/6f6ea4fec6e1e80edb7a6d37e40c0fba16e8bae2f5468cc40200f47433e0d644?s=96&d=mm&r=g","caption":"mtncompany"},"sameAs":["https:\/\/www.garonehabitat.com"],"url":"https:\/\/garonehabitat.com\/es\/author\/mtncompany\/"}]}},"_links":{"self":[{"href":"https:\/\/garonehabitat.com\/es\/wp-json\/wp\/v2\/posts\/27769","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/garonehabitat.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/garonehabitat.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/garonehabitat.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/garonehabitat.com\/es\/wp-json\/wp\/v2\/comments?post=27769"}],"version-history":[{"count":3,"href":"https:\/\/garonehabitat.com\/es\/wp-json\/wp\/v2\/posts\/27769\/revisions"}],"predecessor-version":[{"id":27776,"href":"https:\/\/garonehabitat.com\/es\/wp-json\/wp\/v2\/posts\/27769\/revisions\/27776"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/garonehabitat.com\/es\/wp-json\/wp\/v2\/media\/27771"}],"wp:attachment":[{"href":"https:\/\/garonehabitat.com\/es\/wp-json\/wp\/v2\/media?parent=27769"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/garonehabitat.com\/es\/wp-json\/wp\/v2\/categories?post=27769"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/garonehabitat.com\/es\/wp-json\/wp\/v2\/tags?post=27769"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}