{"id":28633,"date":"2025-10-03T15:08:59","date_gmt":"2025-10-03T13:08:59","guid":{"rendered":"https:\/\/www.garonehabitat.com\/?p=28633"},"modified":"2025-10-27T14:19:03","modified_gmt":"2025-10-27T13:19:03","slug":"garone-awards-serramento-2025-lumina","status":"publish","type":"post","link":"https:\/\/garonehabitat.com\/es\/garone-awards-serramento-2025-lumina\/","title":{"rendered":"Garone trionfa agli Awards del Serramento 2025 con Lumina\u207a"},"content":{"rendered":"<p><span style=\"font-weight: 400;\">Grande soddisfazione per Garone Habitat che, in occasione del <\/span><b>Forum Serramenti &amp; Vetro<\/b><span style=\"font-weight: 400;\">, ha conquistato un nuovo e prestigioso riconoscimento agli <\/span><b>Awards del Serramento<\/b> <b>2025<\/b><span style=\"font-weight: 400;\">, <\/span><span style=\"font-weight: 400;\">assegnato dai lettori del sito <\/span><strong><a href=\"https:\/\/www.guidafinestra.it\/\">guidafinestra.it<\/a><\/strong><span style=\"font-weight: 400;\"> e da una giuria di esperti.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Durante l\u2019evento, svoltosi il 2 ottobre presso il <\/span><b>Savoia Regency Hotel di Bologna<\/b><span style=\"font-weight: 400;\">, l\u2019azienda si \u00e8 distinta nella propria categoria grazie alla qualit\u00e0 e all\u2019innovazione dei suoi infissi <\/span><b>Lumina<\/b><b>\u207a<\/b><span style=\"font-weight: 400;\">, confermandosi ancora una volta punto di riferimento nel settore.<\/span><\/p>\n<h2><b>Gli infissi in legno-alluminio Lumina\u207a<\/b><\/h2>\n<p><span style=\"font-weight: 400;\">Gli <\/span><b>Awards del Serramento<\/b><span style=\"font-weight: 400;\"> sono tra i riconoscimenti pi\u00f9 ambiti del settore, volti a valorizzare i prodotti che meglio incarnano qualit\u00e0, innovazione e design. Considerati ormai un punto di riferimento per produttori, tecnici e professionisti del comparto, certificano l\u2019eccellenza dei serramenti premiati e ne sottolineano il valore in termini di affidabilit\u00e0 e prestazioni.<\/span><\/p>\n<p><a href=\"https:\/\/www.garonehabitat.com\/infissi-lumina-legno-alluminio\/\"><b>Lumina<\/b><b>\u207a<\/b><\/a><span style=\"font-weight: 400;\"> \u00e8 l\u2019infisso in legno alluminio firmato Garone Habitat che ha conquistato la giuria per l\u2019equilibrio tra design, tecnologia e sostenibilit\u00e0. Questo serramento si distingue per il suo stile raffinato ed essenziale, capace di armonizzarsi con ogni contesto abitativo. La struttura interna in legno regala calore e autenticit\u00e0, mentre l\u2019alluminio esterno assicura resistenza agli agenti atmosferici e durata nel tempo. Le prestazioni in termini di isolamento termico e acustico rendono Lumina una soluzione ideale per chi desidera migliorare comfort e benessere domestico, riducendo al contempo i consumi energetici.<\/span><\/p>\n<h2><b>Un altro traguardo per Garone Habitat<\/b><\/h2>\n<p><span style=\"font-weight: 400;\">La vittoria di Garone Habitat con Lumina<\/span>\u207a agli Awards del Serramento 2025<span style=\"font-weight: 400;\">\u00a0rappresenta dunque un traguardo di grande prestigio, che conferma la capacit\u00e0 dell\u2019azienda di combinare materiali nobili e tecnologie all\u2019avanguardia in soluzioni uniche e sostenibili.<\/span><\/p>\n<p><i><span style=\"font-weight: 400;\">\u201cL\u2019anno scorso abbiamo vinto con la finestra legno+legno Linfa e quest\u2019anno con Lumina<\/span><\/i><i>\u207a<\/i><i><span style=\"font-weight: 400;\"> : \u00e8 il coronamento di un percorso lungo 10 anni <\/span><\/i><span style=\"font-weight: 400;\">\u2013 dichiara <\/span><b>Pasquale Garone<\/b><span style=\"font-weight: 400;\">, Direttore Commerciale di Garone Habitat \u2013 <\/span><i><span style=\"font-weight: 400;\">perch\u00e9 questa \u00e8 una finestra nata nel 2016 che abbiamo rivisitato e migliorato. Per questo riconoscimento ci tengo a ringraziare tutti i miei collaboratori\u201d.<\/span><\/i><\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Grande soddisfazione per Garone Habitat che, in occasione del Forum Serramenti &amp; Vetro, ha conquistato un nuovo e prestigioso riconoscimento agli Awards del Serramento 2025, assegnato dai lettori del sito guidafinestra.it e da una giuria di esperti. Durante l\u2019evento, svoltosi il 2 ottobre presso il Savoia Regency Hotel di Bologna, l\u2019azienda si \u00e8 distinta nella [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":28661,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_joinchat":[],"footnotes":""},"categories":[2],"tags":[120,121,124,122,123],"class_list":["post-28633","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-news","tag-awards","tag-eventi","tag-lumina","tag-premi","tag-riconoscimenti"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Garone trionfa agli Awards del Serramento 2025 con Lumina\u207a - Garone Habitat<\/title>\n<meta name=\"description\" content=\"Un altro riconoscimento per Garone Habitat: gli infissi Lumina\u207a sono stati premiati agli Awards del Serramento 2025.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/garonehabitat.com\/es\/garone-awards-serramento-2025-lumina\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Garone trionfa agli Awards del Serramento 2025 con Lumina\u207a - Garone Habitat\" \/>\n<meta property=\"og:description\" content=\"Un altro riconoscimento per Garone Habitat: gli infissi Lumina\u207a sono stati premiati agli Awards del Serramento 2025.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/garonehabitat.com\/es\/garone-awards-serramento-2025-lumina\/\" \/>\n<meta property=\"og:site_name\" content=\"Garone Habitat\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/GaroneHabitat\/\" \/>\n<meta property=\"article:published_time\" content=\"2025-10-03T13:08:59+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-10-27T13:19:03+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/garonehabitat.com\/wp-content\/uploads\/2025\/10\/Garone_awardsdelserramento.png\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"427\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"mtncompany\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"mtncompany\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/garonehabitat.com\\\/es\\\/garone-awards-serramento-2025-lumina\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/garonehabitat.com\\\/es\\\/garone-awards-serramento-2025-lumina\\\/\"},\"author\":{\"name\":\"mtncompany\",\"@id\":\"http:\\\/\\\/new.garonehabitat.com\\\/es\\\/#\\\/schema\\\/person\\\/d446bb2eccc913cfb01e8a4b83c0b2a5\"},\"headline\":\"Garone trionfa agli Awards del Serramento 2025 con Lumina\u207a\",\"datePublished\":\"2025-10-03T13:08:59+00:00\",\"dateModified\":\"2025-10-27T13:19:03+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/garonehabitat.com\\\/es\\\/garone-awards-serramento-2025-lumina\\\/\"},\"wordCount\":330,\"commentCount\":0,\"publisher\":{\"@id\":\"http:\\\/\\\/new.garonehabitat.com\\\/es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/garonehabitat.com\\\/es\\\/garone-awards-serramento-2025-lumina\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/garonehabitat.com\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/Garone_awardsdelserramento.png\",\"keywords\":[\"awards\",\"eventi\",\"lumina\",\"premi\",\"riconoscimenti\"],\"articleSection\":[\"News\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/garonehabitat.com\\\/es\\\/garone-awards-serramento-2025-lumina\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/garonehabitat.com\\\/es\\\/garone-awards-serramento-2025-lumina\\\/\",\"url\":\"https:\\\/\\\/garonehabitat.com\\\/es\\\/garone-awards-serramento-2025-lumina\\\/\",\"name\":\"Garone trionfa agli Awards del Serramento 2025 con Lumina\u207a - Garone Habitat\",\"isPartOf\":{\"@id\":\"http:\\\/\\\/new.garonehabitat.com\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/garonehabitat.com\\\/es\\\/garone-awards-serramento-2025-lumina\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/garonehabitat.com\\\/es\\\/garone-awards-serramento-2025-lumina\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/garonehabitat.com\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/Garone_awardsdelserramento.png\",\"datePublished\":\"2025-10-03T13:08:59+00:00\",\"dateModified\":\"2025-10-27T13:19:03+00:00\",\"description\":\"Un altro riconoscimento per Garone Habitat: gli infissi Lumina\u207a sono stati premiati agli Awards del Serramento 2025.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/garonehabitat.com\\\/es\\\/garone-awards-serramento-2025-lumina\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/garonehabitat.com\\\/es\\\/garone-awards-serramento-2025-lumina\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/garonehabitat.com\\\/es\\\/garone-awards-serramento-2025-lumina\\\/#primaryimage\",\"url\":\"https:\\\/\\\/garonehabitat.com\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/Garone_awardsdelserramento.png\",\"contentUrl\":\"https:\\\/\\\/garonehabitat.com\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/Garone_awardsdelserramento.png\",\"width\":800,\"height\":427},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/garonehabitat.com\\\/es\\\/garone-awards-serramento-2025-lumina\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/garonehabitat.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Garone trionfa agli Awards del Serramento 2025 con Lumina\u207a\"}]},{\"@type\":\"WebSite\",\"@id\":\"http:\\\/\\\/new.garonehabitat.com\\\/es\\\/#website\",\"url\":\"http:\\\/\\\/new.garonehabitat.com\\\/es\\\/\",\"name\":\"Garone Habitat\",\"description\":\"\",\"publisher\":{\"@id\":\"http:\\\/\\\/new.garonehabitat.com\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"http:\\\/\\\/new.garonehabitat.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"http:\\\/\\\/new.garonehabitat.com\\\/es\\\/#organization\",\"name\":\"Garone Habitat\",\"url\":\"http:\\\/\\\/new.garonehabitat.com\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"http:\\\/\\\/new.garonehabitat.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.garonehabitat.com\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/logo-white_garone-1.png\",\"contentUrl\":\"https:\\\/\\\/www.garonehabitat.com\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/logo-white_garone-1.png\",\"width\":149,\"height\":81,\"caption\":\"Garone Habitat\"},\"image\":{\"@id\":\"http:\\\/\\\/new.garonehabitat.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/GaroneHabitat\\\/\"]},{\"@type\":\"Person\",\"@id\":\"http:\\\/\\\/new.garonehabitat.com\\\/es\\\/#\\\/schema\\\/person\\\/d446bb2eccc913cfb01e8a4b83c0b2a5\",\"name\":\"mtncompany\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/6f6ea4fec6e1e80edb7a6d37e40c0fba16e8bae2f5468cc40200f47433e0d644?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/6f6ea4fec6e1e80edb7a6d37e40c0fba16e8bae2f5468cc40200f47433e0d644?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/6f6ea4fec6e1e80edb7a6d37e40c0fba16e8bae2f5468cc40200f47433e0d644?s=96&d=mm&r=g\",\"caption\":\"mtncompany\"},\"sameAs\":[\"https:\\\/\\\/www.garonehabitat.com\"],\"url\":\"https:\\\/\\\/garonehabitat.com\\\/es\\\/author\\\/mtncompany\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Garone trionfa agli Awards del Serramento 2025 con Lumina\u207a - Garone Habitat","description":"Un altro riconoscimento per Garone Habitat: gli infissi Lumina\u207a sono stati premiati agli Awards del Serramento 2025.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/garonehabitat.com\/es\/garone-awards-serramento-2025-lumina\/","og_locale":"es_ES","og_type":"article","og_title":"Garone trionfa agli Awards del Serramento 2025 con Lumina\u207a - Garone Habitat","og_description":"Un altro riconoscimento per Garone Habitat: gli infissi Lumina\u207a sono stati premiati agli Awards del Serramento 2025.","og_url":"https:\/\/garonehabitat.com\/es\/garone-awards-serramento-2025-lumina\/","og_site_name":"Garone Habitat","article_publisher":"https:\/\/www.facebook.com\/GaroneHabitat\/","article_published_time":"2025-10-03T13:08:59+00:00","article_modified_time":"2025-10-27T13:19:03+00:00","og_image":[{"width":800,"height":427,"url":"https:\/\/garonehabitat.com\/wp-content\/uploads\/2025\/10\/Garone_awardsdelserramento.png","type":"image\/png"}],"author":"mtncompany","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"mtncompany","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/garonehabitat.com\/es\/garone-awards-serramento-2025-lumina\/#article","isPartOf":{"@id":"https:\/\/garonehabitat.com\/es\/garone-awards-serramento-2025-lumina\/"},"author":{"name":"mtncompany","@id":"http:\/\/new.garonehabitat.com\/es\/#\/schema\/person\/d446bb2eccc913cfb01e8a4b83c0b2a5"},"headline":"Garone trionfa agli Awards del Serramento 2025 con Lumina\u207a","datePublished":"2025-10-03T13:08:59+00:00","dateModified":"2025-10-27T13:19:03+00:00","mainEntityOfPage":{"@id":"https:\/\/garonehabitat.com\/es\/garone-awards-serramento-2025-lumina\/"},"wordCount":330,"commentCount":0,"publisher":{"@id":"http:\/\/new.garonehabitat.com\/es\/#organization"},"image":{"@id":"https:\/\/garonehabitat.com\/es\/garone-awards-serramento-2025-lumina\/#primaryimage"},"thumbnailUrl":"https:\/\/garonehabitat.com\/wp-content\/uploads\/2025\/10\/Garone_awardsdelserramento.png","keywords":["awards","eventi","lumina","premi","riconoscimenti"],"articleSection":["News"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/garonehabitat.com\/es\/garone-awards-serramento-2025-lumina\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/garonehabitat.com\/es\/garone-awards-serramento-2025-lumina\/","url":"https:\/\/garonehabitat.com\/es\/garone-awards-serramento-2025-lumina\/","name":"Garone trionfa agli Awards del Serramento 2025 con Lumina\u207a - Garone Habitat","isPartOf":{"@id":"http:\/\/new.garonehabitat.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/garonehabitat.com\/es\/garone-awards-serramento-2025-lumina\/#primaryimage"},"image":{"@id":"https:\/\/garonehabitat.com\/es\/garone-awards-serramento-2025-lumina\/#primaryimage"},"thumbnailUrl":"https:\/\/garonehabitat.com\/wp-content\/uploads\/2025\/10\/Garone_awardsdelserramento.png","datePublished":"2025-10-03T13:08:59+00:00","dateModified":"2025-10-27T13:19:03+00:00","description":"Un altro riconoscimento per Garone Habitat: gli infissi Lumina\u207a sono stati premiati agli Awards del Serramento 2025.","breadcrumb":{"@id":"https:\/\/garonehabitat.com\/es\/garone-awards-serramento-2025-lumina\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/garonehabitat.com\/es\/garone-awards-serramento-2025-lumina\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/garonehabitat.com\/es\/garone-awards-serramento-2025-lumina\/#primaryimage","url":"https:\/\/garonehabitat.com\/wp-content\/uploads\/2025\/10\/Garone_awardsdelserramento.png","contentUrl":"https:\/\/garonehabitat.com\/wp-content\/uploads\/2025\/10\/Garone_awardsdelserramento.png","width":800,"height":427},{"@type":"BreadcrumbList","@id":"https:\/\/garonehabitat.com\/es\/garone-awards-serramento-2025-lumina\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/garonehabitat.com\/es\/"},{"@type":"ListItem","position":2,"name":"Garone trionfa agli Awards del Serramento 2025 con Lumina\u207a"}]},{"@type":"WebSite","@id":"http:\/\/new.garonehabitat.com\/es\/#website","url":"http:\/\/new.garonehabitat.com\/es\/","name":"Garone Habitat","description":"","publisher":{"@id":"http:\/\/new.garonehabitat.com\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"http:\/\/new.garonehabitat.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"http:\/\/new.garonehabitat.com\/es\/#organization","name":"Garone Habitat","url":"http:\/\/new.garonehabitat.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"http:\/\/new.garonehabitat.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/www.garonehabitat.com\/wp-content\/uploads\/2024\/05\/logo-white_garone-1.png","contentUrl":"https:\/\/www.garonehabitat.com\/wp-content\/uploads\/2024\/05\/logo-white_garone-1.png","width":149,"height":81,"caption":"Garone Habitat"},"image":{"@id":"http:\/\/new.garonehabitat.com\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/GaroneHabitat\/"]},{"@type":"Person","@id":"http:\/\/new.garonehabitat.com\/es\/#\/schema\/person\/d446bb2eccc913cfb01e8a4b83c0b2a5","name":"mtncompany","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/6f6ea4fec6e1e80edb7a6d37e40c0fba16e8bae2f5468cc40200f47433e0d644?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/6f6ea4fec6e1e80edb7a6d37e40c0fba16e8bae2f5468cc40200f47433e0d644?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/6f6ea4fec6e1e80edb7a6d37e40c0fba16e8bae2f5468cc40200f47433e0d644?s=96&d=mm&r=g","caption":"mtncompany"},"sameAs":["https:\/\/www.garonehabitat.com"],"url":"https:\/\/garonehabitat.com\/es\/author\/mtncompany\/"}]}},"_links":{"self":[{"href":"https:\/\/garonehabitat.com\/es\/wp-json\/wp\/v2\/posts\/28633","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/garonehabitat.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/garonehabitat.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/garonehabitat.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/garonehabitat.com\/es\/wp-json\/wp\/v2\/comments?post=28633"}],"version-history":[{"count":6,"href":"https:\/\/garonehabitat.com\/es\/wp-json\/wp\/v2\/posts\/28633\/revisions"}],"predecessor-version":[{"id":28660,"href":"https:\/\/garonehabitat.com\/es\/wp-json\/wp\/v2\/posts\/28633\/revisions\/28660"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/garonehabitat.com\/es\/wp-json\/wp\/v2\/media\/28661"}],"wp:attachment":[{"href":"https:\/\/garonehabitat.com\/es\/wp-json\/wp\/v2\/media?parent=28633"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/garonehabitat.com\/es\/wp-json\/wp\/v2\/categories?post=28633"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/garonehabitat.com\/es\/wp-json\/wp\/v2\/tags?post=28633"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}